{"id":29986,"date":"2023-04-13T11:45:52","date_gmt":"2023-04-13T11:45:52","guid":{"rendered":"https:\/\/www.ipsen.com\/?page_id=76"},"modified":"2026-08-19T21:23:25","modified_gmt":"2026-08-19T19:23:25","slug":"leadership-team","status":"publish","type":"page","link":"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/","title":{"rendered":"Leadership"},"content":{"rendered":"    <section class=\"sub-page-banner bg-img-enabled  banner-no-filter\" style=\"background-image:url(https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2025\/07\/Company-Leadership.jpg)\">\n\n                <div class=\"container content-sec\">\n            <nav aria-label=\"breadcrumb banner-font-color-blue\">\n            <ol class=\"breadcrumb\">\n                <li class=\"breadcrumb-item\"><a href=\"https:\/\/www.ipsen.com\/us\">Home<\/a><\/li><li class=\"breadcrumb-item visible\"><a href=\"https:\/\/www.ipsen.com\/us\/company\/\">Who We Are<\/a><\/li><li class=\"breadcrumb-item active\"><a class=\"link-pointer-events-none\" href=\"#\" aria-current=\"page\">Leadership<\/a><\/li><\/ol>\n            <\/nav>            <h1 class=\"visible banner-font-color-white\">Leadership<\/h1>\n            <p class=\"hidden banner-font-color-white\"><\/p>\n        <\/div>\n    <\/section>\n\n\n\n\n\n    <div class=\"container tab-pane-container\" >\n        <section class=\"profile-card\">\n            <div class=\"profile-regular-listing\">\n    <div class=\"container regular-listing-container\">\n        <h3 role=\"heading\" aria-level=\"2\" class=\"profile-head visible heading-three\">Meet our leadership team<\/h3>\n        <p class=\"profile-summary hidden\"><\/p>\n        <div class=\"regular-lisitng\">\n            <div class=\"row\">\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/michelle-werner\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2026\/03\/ALLTRNA_5_24_33431-web_ipsen-US-web.jpg\" alt=\"Michelle Werner\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Michelle Werner                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Executive Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                President of North America                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/abla-abrial\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2025\/01\/Abla-Abrial_Headshot.png\" alt=\"Abla Abrial\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Abla Abrial                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Senior Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Head of Finance, North America                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/kimberly-baldwin\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2023\/06\/Kimberly-Baldwin.jpg\" alt=\"Kimberly Baldwin\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Kimberly Baldwin                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Senior Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Value &amp; Access                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/ed-dybka\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2023\/06\/Ed-Dybka.jpg\" alt=\"Ed Dybka\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Ed Dybka                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                General Manager                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Ipsen Canada                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/liz-kalina\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2023\/06\/Liz-Kalina.jpg\" alt=\"Liz Kalina\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Liz Kalina                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Corporate Affairs                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/agnes-lteif\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2025\/09\/Agnes-Lteif_Headshot-1.png\" alt=\"Agnes Lteif, MD\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Agnes Lteif, MD                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Senior Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Head of Medical Affairs and Regulatory, North America                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/rebecca_milbury\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2026\/04\/Rebecca-Milbury_Ipsen-US-Headshot_April-2026.jpg\" alt=\"Rebecca Milbury\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Rebecca Milbury                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main hidden\">\n                                                                                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Head of Human Resources, North America                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/eduardo-molina\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2024\/09\/Eduardo-Molina_Headshot.png\" alt=\"Eduardo Molina\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Eduardo Molina                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Business Operations &amp; Strategy and Chief of Staff                                                             <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/jesse-siegel\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2024\/09\/Jesse-Siegel_Headshot-1.png\" alt=\"Jesse Siegel\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Jesse Siegel                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main hidden\">\n                                                                                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Head of U.S. Business Ethics                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/lindy-wallick\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2026\/07\/Lindy-Wallick_Headshot.png\" alt=\"Lindy Wallick\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Lindy Wallick                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Senior Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Franchise Head, Rare Disease Business Unit                                                             <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                                            <div class=\"col-lg-4 col-md-6 col-sm-12\">\n                                <div class=\"profile-regular-card\">\n\n                                        <div class=\"profile-regular-card-inner\">\n                                                                                            <a href=\"https:\/\/www.ipsen.com\/us\/leadership\/chris-watters\/\">\n                                                \n                                            \n                                                <div class=\"profile-card-img\">\n                                                    <img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2023\/06\/Chris-Watters.jpg\" alt=\"Chris Watters\" \/>\n                                                <\/div>\n                                                <div class=\"profile-details-sec\">\n                                                    <h3 role=\"heading\" aria-level=\"3\" class=\"profile-title-para\">\n                                                        Chris Watters                                                    <\/h3>\n                                                    <div class=\"role-sec\">\n                                                        <p>\n                                                            <span class=\"profile-main visible\">\n                                                                Vice President                                                            <\/span>\n                                                        <\/p>\n                                                        <div class=\"profile-dec-sec visible\">\n                                                            <p class=\"profile-role-desc\">\n                                                                Franchise Head, Neuroscience Business Unit                                                            <\/p>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                                                                            <\/a>\n                                                \n\n                                        <\/div>\n\n                                <\/div>\n                            <\/div>\n                \n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>        <\/section>\n    <\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":29975,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-29986","page","type-page","status-publish","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ipsen\u2019s Executive Leadership Team and Board of Directors<\/title>\n<meta name=\"description\" content=\"Meet the members of Ipsen\u2019s Executive Leadership Team and Board of Directors.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ipsen\u2019s Executive Leadership Team and Board of Directors\" \/>\n<meta property=\"og:description\" content=\"Meet the members of Ipsen\u2019s Executive Leadership Team and Board of Directors.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/\" \/>\n<meta property=\"og:site_name\" content=\"United States\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-19T19:23:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/leadership-team\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/leadership-team\\\/\",\"name\":\"Ipsen\u2019s Executive Leadership Team and Board of Directors\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/#website\"},\"datePublished\":\"2023-04-13T11:45:52+00:00\",\"dateModified\":\"2026-08-19T19:23:25+00:00\",\"description\":\"Meet the members of Ipsen\u2019s Executive Leadership Team and Board of Directors.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/leadership-team\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/leadership-team\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/leadership-team\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Who We Are\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Leadership\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/\",\"name\":\"United States\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/#organization\",\"name\":\"United States\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"United States\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/us\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ipsen\u2019s Executive Leadership Team and Board of Directors","description":"Meet the members of Ipsen\u2019s Executive Leadership Team and Board of Directors.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/","og_locale":"en_US","og_type":"article","og_title":"Ipsen\u2019s Executive Leadership Team and Board of Directors","og_description":"Meet the members of Ipsen\u2019s Executive Leadership Team and Board of Directors.","og_url":"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/","og_site_name":"United States","article_modified_time":"2026-08-19T19:23:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/","url":"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/","name":"Ipsen\u2019s Executive Leadership Team and Board of Directors","isPartOf":{"@id":"https:\/\/www.ipsen.com\/us\/#website"},"datePublished":"2023-04-13T11:45:52+00:00","dateModified":"2026-08-19T19:23:25+00:00","description":"Meet the members of Ipsen\u2019s Executive Leadership Team and Board of Directors.","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/us\/company\/leadership-team\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/us\/company\/leadership-team\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/us\/"},{"@type":"ListItem","position":2,"name":"Who We Are","item":"https:\/\/www.ipsen.com\/us\/company\/"},{"@type":"ListItem","position":3,"name":"Leadership"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/us\/#website","url":"https:\/\/www.ipsen.com\/us\/","name":"United States","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/us\/#organization","name":"United States","url":"https:\/\/www.ipsen.com\/us\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ipsen.com\/us\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/us\/wp-content\/uploads\/sites\/2\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"United States"},"image":{"@id":"https:\/\/www.ipsen.com\/us\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/ipsen.com\/us\/company\/leadership-team\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"WebPage","headline":"Leadership","url":"http:\/\/www.ipsen.com\/us\/company\/leadership-team\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.ipsen.com\/us\/company\/leadership-team\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"General","author":[{"@type":"Person","name":"devops"}],"creator":["devops"],"publisher":{"@type":"Organization","name":"United States","logo":""},"keywords":[],"dateCreated":"2023-04-13T11:45:52Z","datePublished":"2023-04-13T11:45:52Z","dateModified":"2026-08-19T19:23:25Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"WebPage\",\"headline\":\"Leadership\",\"url\":\"http:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/leadership-team\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.ipsen.com\\\/us\\\/company\\\/leadership-team\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"General\",\"author\":[{\"@type\":\"Person\",\"name\":\"devops\"}],\"creator\":[\"devops\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"United States\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-04-13T11:45:52Z\",\"datePublished\":\"2023-04-13T11:45:52Z\",\"dateModified\":\"2026-08-19T19:23:25Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/ipsen.com\/p.js"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/pages\/29986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/comments?post=29986"}],"version-history":[{"count":38,"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/pages\/29986\/revisions"}],"predecessor-version":[{"id":56389,"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/pages\/29986\/revisions\/56389"}],"up":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/pages\/29975"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/us\/wp-json\/wp\/v2\/media?parent=29986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}