{"id":28530,"date":"2022-06-21T09:00:00","date_gmt":"2022-06-21T09:00:00","guid":{"rendered":"https:\/\/www.ipsen.com\/press-releases\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/"},"modified":"2024-07-24T09:14:53","modified_gmt":"2024-07-24T07:14:53","slug":"programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022","status":"publish","type":"press_release","link":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/","title":{"rendered":"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022"},"content":{"rendered":"<p class=\"heading-para wp-block-paragraph\"><em>Cet article ou communiqu\u00e9 de presse n&#8217;a pas de contenu en ligne. <\/em><em>Veuillez t\u00e9l\u00e9charger les documents associ\u00e9s pour plus d&#8217;informations.<\/em><\/p>\n\n<p id=\"gnw_attachments_section-header\" class=\"heading-para wp-block-paragraph\"><strong>Pi\u00e8ce jointe<\/strong><\/p>\n\n\n<ul class=\"wp-block-list\" id=\"gnw_attachments_section-items\">\n<li><a title=\"Programme-de-rachat-dactions-reporting-detaille-Ipsen-du-13-juin-au-17-juin-2022\" href=\"https:\/\/www.globenewswire.com\/Tracker?data=K0SceHB4gVuPbsSqDUfogG2Z-H1wItxeRrlR1sRnpRDtCIoKitQ9kCEyGJRmeRBVhayWo7jqVniCZyvHnnWJvMmHC0aqgdKDqp9gwnGsNomc1NXK3gWJZy16YALYUvxFHEk9qSY5xAfQuq2yydiYvjOpS3lphEvRhyq0SwEbEJ53stOJ_C_6KOvz2qtMUOalUx1E22r2w7dyS7gDFZu3YKMrtF0Qwa4xXiv_sqD9RyGD8MIJ1enued1LptGlERo1\" target=\"_blank\" rel=\"nofollow noopener\">Programme-de-rachat-dactions-reporting-detaille-Ipsen-du-13-juin-au-17-juin-2022<\/a><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/ml-eu.globenewswire.com\/media\/YWNkNjlhZDctYmZmYi00NDhhLWI4YjYtZThjNzg2MmExMWM0LTEwMTA5NDM=\/tiny\/Ipsen-SA.png\" alt=\"\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Cet article ou communiqu\u00e9 de presse n&#8217;a pas de contenu en ligne. Veuillez t\u00e9l\u00e9charger les documents associ\u00e9s pour plus d&#8217;informations. Pi\u00e8ce jointe<\/p>\n","protected":false},"author":5,"template":"","categories":[1233,6364],"tags":[],"class_list":["post-28530","press_release","type-press_release","status-publish","has-post-thumbnail","hentry","category-pressrelease-fr","category-regulated-info-fr","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022\" \/>\n<meta property=\"og:description\" content=\"Cet article ou communiqu\u00e9 de presse n&#8217;a pas de contenu en ligne. Veuillez t\u00e9l\u00e9charger les documents associ\u00e9s pour plus d&#8217;informations. Pi\u00e8ce jointe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-24T07:14:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipsen.com\/wp-content\/uploads\/2022\/08\/PR-final-fr-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1082\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022\",\"datePublished\":\"2022-06-21T09:00:00+00:00\",\"dateModified\":\"2024-07-24T07:14:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/\"},\"wordCount\":44,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/PR-final-fr-1.jpeg\",\"articleSection\":[\"Communiqu\u00e9 de presse\",\"Informations r\u00e9glement\u00e9es\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/\",\"name\":\"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/PR-final-fr-1.jpeg\",\"datePublished\":\"2022-06-21T09:00:00+00:00\",\"dateModified\":\"2024-07-24T07:14:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/PR-final-fr-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/PR-final-fr-1.jpeg\",\"width\":1082,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/communique-de-presse\\\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"name\":\"Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\",\"name\":\"IPSEN\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"IPSEN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ipsengroup\",\"https:\\\/\\\/x.com\\\/ipsengroup\"]},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/","og_locale":"fr_FR","og_type":"article","og_title":"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022","og_description":"Cet article ou communiqu\u00e9 de presse n&#8217;a pas de contenu en ligne. Veuillez t\u00e9l\u00e9charger les documents associ\u00e9s pour plus d&#8217;informations. Pi\u00e8ce jointe","og_url":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/","og_site_name":"Global","article_modified_time":"2024-07-24T07:14:53+00:00","og_image":[{"width":1082,"height":620,"url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2022\/08\/PR-final-fr-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@ipsengroup","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/#article","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/"},"author":{"name":"","@id":""},"headline":"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022","datePublished":"2022-06-21T09:00:00+00:00","dateModified":"2024-07-24T07:14:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/"},"wordCount":44,"publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2022\/08\/PR-final-fr-1.jpeg","articleSection":["Communiqu\u00e9 de presse","Informations r\u00e9glement\u00e9es"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/","url":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/","name":"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2022\/08\/PR-final-fr-1.jpeg","datePublished":"2022-06-21T09:00:00+00:00","dateModified":"2024-07-24T07:14:53+00:00","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/#primaryimage","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2022\/08\/PR-final-fr-1.jpeg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2022\/08\/PR-final-fr-1.jpeg","width":1082,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/fr\/communique-de-presse\/programme-de-rachat-dactions-reporting-detaille-ipsen-du-13-juin-au-17-juin-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Programme de rachat d\u2019actions \u2013 reporting d\u00e9taill\u00e9 Ipsen du 13 juin au 17 juin 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/fr\/#website","url":"https:\/\/www.ipsen.com\/fr\/","name":"Global","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/fr\/#organization","name":"IPSEN","url":"https:\/\/www.ipsen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"IPSEN"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ipsengroup","https:\/\/x.com\/ipsengroup"]},{"@type":"Person","@id":""}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/press_release\/28530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/types\/press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"version-history":[{"count":1,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/press_release\/28530\/revisions"}],"predecessor-version":[{"id":62743,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/press_release\/28530\/revisions\/62743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media\/27874"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media?parent=28530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/categories?post=28530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/tags?post=28530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}