{"id":60692,"date":"2024-06-26T16:24:22","date_gmt":"2024-06-26T14:24:22","guid":{"rendered":"https:\/\/www.ipsen.com\/?p=60692"},"modified":"2024-06-26T16:28:47","modified_gmt":"2024-06-26T14:28:47","slug":"lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen","status":"publish","type":"post","link":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/","title":{"rendered":"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0"},"content":{"rendered":"<p class=\"heading-para wp-block-paragraph\">Lorsqu\u2019Eric Gratton a rejoint Ipsen apr\u00e8s avoir travaill\u00e9 au sein d\u2019une grande soci\u00e9t\u00e9 de services financiers, il a \u00e9t\u00e9 surpris de constater qu\u2019il n\u2019existait pas de groupe de ressources pour les employ\u00e9s (Employee Ressource Group, ERG) d\u00e9di\u00e9 \u00e0 la communaut\u00e9 LGBTQIA+. \u00ab\u202fToujours pr\u00eat \u00e0 relever de nouveaux d\u00e9fis, je me suis dit qu\u2019il fallait que je cr\u00e9e un groupe : ce fut un projet-passion, que j\u2019ai entrepris pour la communaut\u00e9 et ses alli\u00e9s.\u202f\u00bb En s\u2019inspirant d\u2019Elevate, l\u2019ERG d\u2019Ipsen d\u00e9di\u00e9 aux femmes, Eric a commenc\u00e9 \u00e0 esquisser l\u2019id\u00e9e d\u2019un ERG global.\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">\u00ab\u202fNous avons tout d\u2019abord organis\u00e9 un \u00e9v\u00e9nement de brainstorming pour r\u00e9fl\u00e9chir \u00e0 un nom, \u00e9tablir une charte et d\u00e9finir nos valeurs. Nous avons lanc\u00e9 Spectra en juin de l\u2019ann\u00e9e derni\u00e8re, pendant le mois des fiert\u00e9s,\u202f\u00bb a d\u00e9clar\u00e9 Sam Baily. Bien que le bureau d\u2019Ipsen \u00e0 Cambridge (Massachusetts) collaborait d\u00e9j\u00e0 avec OUTbio, le plus grand groupe de professionnels LGBTQIA+ de l\u2019industrie biotechnologique, l\u2019\u00e9quipe aspirait \u00e0 pousser son engagement encore plus loin.\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">\u00ab\u202fAline Stokes, notre directrice globale DE&amp;I (diversit\u00e9, \u00e9quit\u00e9, inclusion), nous a pr\u00e9sent\u00e9s, car elle savait que nous partagions une vocation commune pour l\u2019inclusion LGBTQIA+. Nous avons form\u00e9 une r\u00e9elle \u00e9quipe et cr\u00e9\u00e9 Spectra peu de temps apr\u00e8s,\u202f\u00bb a expliqu\u00e9 Sam. \u00ab Notre ambition est que Spectra devienne une ressource pr\u00e9cieuse pour les personnes qui travaillent chez Ipsen et pour l\u2019entreprise, notamment en contribuant \u00e0 l\u2019\u00e9laboration de politiques et, au-del\u00e0, en influen\u00e7ant les communaut\u00e9s scientifiques et de la sant\u00e9 au sens large en faveur de notre cause. Nous travaillons, par exemple, avec des prestataires de soins de sant\u00e9 pour les aider \u00e0 comprendre l\u2019importance d\u2019utiliser les bons pronoms et s\u2019assurer qu\u2019ils sont attentifs \u00e0 l\u2019exp\u00e9rience du patient.\u202f\u00bb\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Courtney Anderson a rejoint Spectra peu apr\u00e8s sa cr\u00e9ation. \u00ab\u202fJ\u2019ai rejoint l\u2019organisation en tant qu\u2019alli\u00e9e LGBTQIA+ et je suis fi\u00e8re du chemin que notre groupe a parcouru. Nous savions que nous avions besoin de l\u2019aide des membres de la direction pour faire entendre notre voix, et nous travaillons aujourd\u2019hui avec le soutien de nos sponsors de la Leadership Team Am\u00e9rique du Nord. Je collabore \u00e9galement avec OUTbio pour planifier un sommet (\u00ab\u202fERG Summit\u202f\u00bb) \u00e0 l\u2019automne. J\u2019ai d\u00e9j\u00e0 organis\u00e9 divers \u00e9v\u00e9nements cette ann\u00e9e, notamment une table ronde sur le r\u00f4le cl\u00e9 que les employeurs comme Ipsen peuvent jouer dans les actions de plaidoyer en faveur du progr\u00e8s.\u202f\u00bb\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Au-del\u00e0 de la branche Am\u00e9rique du Nord de Spectra, qui compte des antennes \u00e0 Cambridge et \u00e0 Montr\u00e9al, la branche de Spectra au Royaume-Uni et en Irlande est particuli\u00e8rement active. Sam s\u2019implique dans des projets DE&amp;I depuis plusieurs ann\u00e9es, et a notamment lanc\u00e9 un ERG similaire au sein d\u2019une autre entreprise dans le cadre d\u2019une pr\u00e9c\u00e9dente exp\u00e9rience professionnelle. \u00ab Lorsque j\u2019ai rejoint Ipsen, aucun ERG n\u2019existait. J\u2019ai observ\u00e9 de nombreux changements ces derni\u00e8res ann\u00e9es. Au d\u00e9part, nous avions un groupe qui travaillait en faveur de la diversit\u00e9 au sens large. Avec Spectra, nous concentrons nos efforts sur la communaut\u00e9 LGBTQIA+, en contribuant \u00e0 la mise en \u0153uvre de politiques et en sensibilisant l\u2019ensemble des salari\u00e9s d\u2019Ipsen. Le lancement de Spectra a \u00e9t\u00e9 pour nous une opportunit\u00e9 de collaborer \u00e9troitement et de b\u00e9n\u00e9ficier des ressources de chacun.\u202f\u00bb\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Spectra est guid\u00e9e par une vision, une mission et une charte claires\u202f:\u00a0<\/p>\n\n\n<ul class=\"wp-block-list\">\n<li>Vision\u202f: Donner aux coll\u00e8gues et aux proches, au sein de la communaut\u00e9 LGBTQIA+ les moyens de contribuer aux actions de plaidoyer, d\u2019\u00e9ducation, de d\u00e9veloppement professionnel et de sensibilisation communautaire.\u00a0<\/li>\n\n\n\n<li>Mission\u202f: Mettre en valeur et c\u00e9l\u00e9brer les perspectives et exp\u00e9riences des communaut\u00e9s LGBTQIA+ au sein d\u2019Ipsen.\u00a0<\/li>\n\n\n\n<li>Charte\u202f: Nous valorisons les contributions de chaque personne et visons \u00e0 cr\u00e9er un environnement bienveillant pour les communaut\u00e9s LGBTQIA+ chez Ipsen. Nous pensons qu\u2019il s\u2019agit d\u2019une \u00e9tape essentielle dans la cr\u00e9ation d\u2019un lieu de travail plus inclusif et \u00e9quitable.\u00a0<\/li>\n<\/ul>\n\n\n<p class=\"heading-para wp-block-paragraph\">Pour l\u2019avenir, les co-pr\u00e9sidents ont d\u00e9fini des objectifs ambitieux au-del\u00e0 des actions visant \u00e0 c\u00e9l\u00e9brer la communaut\u00e9. Ces objectifs visent \u00e0 \u00e9laborer des politiques qui favoriseront une utilisation appropri\u00e9e des pronoms, \u00e0 soutenir les personnes qui effectuent leur transition de genre et \u00e0 am\u00e9liorer les avantages sociaux. \u00ab\u202fCe dont nous avons le plus besoin, ce sont des personnes qui sont pr\u00eates \u00e0 apporter leur contribution pour intensifier nos actions,\u202f\u00bb a d\u00e9clar\u00e9 Eric. \u00ab\u202fNous voulons que Spectra soit p\u00e9renne,\u202f\u00bb a ajout\u00e9 Courtney. \u00ab\u202fNotre groupe doit continuer d\u2019exister m\u00eame si un jour nous ne sommes plus l\u00e0.\u202f\u00bb\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Nous nous r\u00e9jouissons des r\u00e9alisations \u00e0 venir de Spectra en mati\u00e8re de promotion de l\u2019inclusion et de l\u2019\u00e9quit\u00e9, qui visent \u00e0 cr\u00e9er un lieu de travail diversifi\u00e9 et solidaire, au b\u00e9n\u00e9fice de tous.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Lorsqu\u2019Eric Gratton a rejoint Ipsen apr\u00e8s avoir travaill\u00e9 au sein d\u2019une grande soci\u00e9t\u00e9 de services financiers, il a \u00e9t\u00e9 surpris<\/p>\n","protected":false},"author":11,"featured_media":60690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[24935,24928],"tags":[],"class_list":["post-60692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture-fr","category-durabilite","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0 - Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0 - Global\" \/>\n<meta property=\"og:description\" content=\"Lorsqu\u2019Eric Gratton a rejoint Ipsen apr\u00e8s avoir travaill\u00e9 au sein d\u2019une grande soci\u00e9t\u00e9 de services financiers, il a \u00e9t\u00e9 surpris\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-26T14:24:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-26T14:28:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/06\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1082\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"heloisedetouchet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:site\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"heloisedetouchet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/\"},\"author\":{\"name\":\"heloisedetouchet\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/2c275168b31beee81688f3c041877318\"},\"headline\":\"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0\",\"datePublished\":\"2024-06-26T14:24:22+00:00\",\"dateModified\":\"2024-06-26T14:28:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/\"},\"wordCount\":876,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg\",\"articleSection\":[\"Culture\",\"Durabilit\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/\",\"name\":\"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0 - Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg\",\"datePublished\":\"2024-06-26T14:24:22+00:00\",\"dateModified\":\"2024-06-26T14:28:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg\",\"width\":1082,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/culture-fr\\\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"name\":\"Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\",\"name\":\"IPSEN\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"IPSEN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ipsengroup\",\"https:\\\/\\\/x.com\\\/ipsengroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/2c275168b31beee81688f3c041877318\",\"name\":\"heloisedetouchet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g\",\"caption\":\"heloisedetouchet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0 - Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0 - Global","og_description":"Lorsqu\u2019Eric Gratton a rejoint Ipsen apr\u00e8s avoir travaill\u00e9 au sein d\u2019une grande soci\u00e9t\u00e9 de services financiers, il a \u00e9t\u00e9 surpris","og_url":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/","og_site_name":"Global","article_published_time":"2024-06-26T14:24:22+00:00","article_modified_time":"2024-06-26T14:28:47+00:00","og_image":[{"width":1082,"height":620,"url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/06\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg","type":"image\/jpeg"}],"author":"heloisedetouchet","twitter_card":"summary_large_image","twitter_creator":"@ipsengroup","twitter_site":"@ipsengroup","twitter_misc":{"Written by":"heloisedetouchet","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/#article","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/"},"author":{"name":"heloisedetouchet","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/2c275168b31beee81688f3c041877318"},"headline":"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0","datePublished":"2024-06-26T14:24:22+00:00","dateModified":"2024-06-26T14:28:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/"},"wordCount":876,"publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/06\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg","articleSection":["Culture","Durabilit\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/","url":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/","name":"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0 - Global","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/#primaryimage"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/06\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg","datePublished":"2024-06-26T14:24:22+00:00","dateModified":"2024-06-26T14:28:47+00:00","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/#primaryimage","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/06\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/06\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg","width":1082,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/culture-fr\/lerg-spectra-celebre-sa-premiere-annee-dexistence-en-soutien-a-la-communaute-lgbtqia-dipsen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019ERG Spectra c\u00e9l\u00e8bre sa premi\u00e8re ann\u00e9e d\u2019existence en soutien \u00e0 la communaut\u00e9 LGBTQIA+ d\u2019Ipsen\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/fr\/#website","url":"https:\/\/www.ipsen.com\/fr\/","name":"Global","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/fr\/#organization","name":"IPSEN","url":"https:\/\/www.ipsen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"IPSEN"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ipsengroup","https:\/\/x.com\/ipsengroup"]},{"@type":"Person","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/2c275168b31beee81688f3c041877318","name":"heloisedetouchet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g","caption":"heloisedetouchet"}}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/06\/202406_Pride-Month_Ipsen-com_1082x620pix.jpg","_links":{"self":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/60692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/comments?post=60692"}],"version-history":[{"count":1,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/60692\/revisions"}],"predecessor-version":[{"id":60693,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/60692\/revisions\/60693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media\/60690"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media?parent=60692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/categories?post=60692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/tags?post=60692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}