{"id":34000,"date":"2023-06-26T08:56:53","date_gmt":"2023-06-26T06:56:53","guid":{"rendered":"https:\/\/www.ipsen.com\/?p=34000"},"modified":"2024-05-21T14:43:40","modified_gmt":"2024-05-21T12:43:40","slug":"john-raconte-son-quotidien-avec-le-cancer-de-la-prostate","status":"publish","type":"post","link":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/","title":{"rendered":"John raconte son quotidien avec le cancer de la prostate"},"content":{"rendered":"<p class=\"heading-para wp-block-paragraph\">Recevoir un diagnostic de cancer peut \u00eatre accablant. Cependant, les effets du cancer de la prostate peuvent \u00eatre nuanc\u00e9s pour les hommes qui en sont atteints. John, originaire du Royaume-Uni, \u00e9tait \u00e2g\u00e9 d&#8217;une cinquantaine d&#8217;ann\u00e9es lorsqu&#8217;il a appris qu&#8217;il \u00e9tait atteint d&#8217;un cancer de la prostate. Il a souhait\u00e9 raconter son histoire pour encourager les hommes \u00e0 consulter un m\u00e9decin s&#8217;ils pr\u00e9sentent des sympt\u00f4mes, et pour rassurer ceux qui pourraient \u00eatre diagnostiqu\u00e9s de ce cancer.<\/p>\n\n    <section class=\"video-card \">\n        <div class=\"container\">\n            <!-- Block Details -->\n            <div class=\"video-card-header\">\n                <h3 class=\"video-card-block-title hidden heading-three\">\n                                    <\/h3>\n                <p class=\"charcoal-grey video-card-block-summary hidden\"> \n                                    <\/p>\n            <\/div>\n\n            <!-- Video Iframe embed -->\n                            <div class=\"video-embed\"> \n                <iframe loading=\"lazy\" title=\"Prostate patient film For a Chance John_FRENCH\" src=\"https:\/\/player.vimeo.com\/video\/838315799?app_id=122963&#038;autoplay=1&#038;muted=1&#038;controls=1&#038;loop=1&#038;autopause=1&#038;background=0\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" id=\"ipsen-video-1\" class=\"veeva_video\" data-ot-ignore><\/iframe>                <\/div>\n            \n            <!-- Block CTA -->\n            <div class=\"cta-block hidden\">\n                            <\/div>\n\n        <\/div>\n    <\/section>\n\n\n<p class=\"heading-para wp-block-paragraph\"><strong>Je pensais que les sympt\u00f4mes \u00e9taient ceux du \u00ab\u00a0syndrome du vieil homme\u00a0\u00bb.<\/strong><\/p>\n\n<p class=\"heading-para wp-block-paragraph\">\u00ab\u00a0Il y a quelques ann\u00e9es, j&#8217;allais de nombreuses fois aux toilettes la nuit pour uriner. Je sais que j&#8217;y allais beaucoup, parce que ma femme n&#8217;arr\u00eatait pas de me dire que j&#8217;interrompais son sommeil ! Elle m&#8217;a demand\u00e9 de consulter un m\u00e9decin \u00e0 ce sujet. Je pensais qu&#8217;il s&#8217;agissait simplement d&#8217;un sympt\u00f4me qu&#8217;ont les hommes plus \u00e2g\u00e9s \u2013 je l&#8217;ai appel\u00e9 le \u00ab\u00a0syndrome du vieil homme\u00a0\u00bb, mais il s&#8217;est av\u00e9r\u00e9 que quelque chose n&#8217;allait pas. J&#8217;ai la chance d&#8217;avoir des amis dont je me sens suffisamment proche pour parler de probl\u00e8mes de sant\u00e9. Un jour, j&#8217;ai racont\u00e9 \u00e0 l&#8217;un d&#8217;eux que je me levais 4 ou 5 fois par nuit pour uriner, en esp\u00e9rant qu&#8217;il me dirait la m\u00eame chose. Mais il a confirm\u00e9 ce que ma femme pensait\u00a0: ce n&#8217;\u00e9tait pas normal et je devais aller consulter un m\u00e9decin.\u00a0\u00bb<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">La plupart des hommes atteints d\u2019un cancer de la prostate au stade pr\u00e9coce ne pr\u00e9sentent aucun signe ni sympt\u00f4me.<br>Lorsque les sympt\u00f4mes apparaissent, le cancer a g\u00e9n\u00e9ralement commenc\u00e9 \u00e0 se d\u00e9velopper pr\u00e8s de l&#8217;ur\u00e8tre ou \u00e0 s&#8217;appuyer contre, ce qui g\u00e9n\u00e8re des probl\u00e8mes pour uriner, similaires \u00e0 ceux de John. Le patient peut notamment ressentir des difficult\u00e9s \u00e0 uriner au d\u00e9but de la miction ou \u00e0 vider sa vessie, avec un faible d\u00e9bit lors de la miction\u00a0; avoir la sensation que la vessie ne s&#8217;est pas vid\u00e9e correctement\u00a0; \u00e9prouver le besoin d&#8217;uriner plus souvent que d&#8217;habitude, surtout la nuit\u00a0; et avoir soudainement besoin d&#8217;uriner. Bien que ces changements puissent souvent \u00eatre le sympt\u00f4me d&#8217;une hypertrophie de la prostate ou d&#8217;un autre probl\u00e8me de sant\u00e9, il est toujours conseill\u00e9 de se rendre chez un m\u00e9decin g\u00e9n\u00e9raliste pour se faire examiner.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\"><strong>J&#8217;envisageais le pire au d\u00e9but, mais je suis toujours l\u00e0 aujourd&#8217;hui\u00a0!<\/strong><\/p>\n\n<p class=\"heading-para wp-block-paragraph\">\u00ab\u00a0Je me suis donc rendu chez le m\u00e9decin g\u00e9n\u00e9raliste et, apr\u00e8s un examen et des analyses de sang, j&#8217;ai \u00e9t\u00e9 orient\u00e9 vers un sp\u00e9cialiste qui m&#8217;a inform\u00e9 que j&#8217;avais un cancer. Les premi\u00e8res 24 heures qui ont suivi le diagnostic ont \u00e9t\u00e9 terrifiantes, j&#8217;ai cru que j&#8217;allais mourir sur-le-champ. Vous redoutez le pire lorsque vous entendez le mot \u00ab cancer \u00bb. Mais ce n&#8217;est manifestement pas le cas, puisque je suis toujours l\u00e0 des ann\u00e9es plus tard\u00a0!<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Malheureusement, il y a encore une forte stigmatisation li\u00e9e au cancer de la prostate, qui va au-del\u00e0 des probl\u00e8mes physiques associ\u00e9s \u00e0 ce cancer. Une \u00e9tude datant de 2020 montre que de nombreuses personnes atteintes d&#8217;un cancer de la prostate se sentent stigmatis\u00e9es et embarrass\u00e9es. Certaines consid\u00e8rent la maladie comme \u00e9tant \u00ab\u00a0\u00e9masculante\u00a0\u00bb, tandis que d&#8217;autres h\u00e9sitent \u00e0 en parler avec des amis ou des membres de leur famille en raison des conventions sociales qui imposent la discr\u00e9tion sur ce genre de sujet. Il est essentiel de mettre un terme \u00e0 la stigmatisation et la honte associ\u00e9es au cancer de la prostate pour que les hommes demandent et re\u00e7oivent un diagnostic le plus t\u00f4t possible, et se sentent soutenus pendant leur traitement.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\"><strong>J&#8217;encourage les hommes atteints d&#8217;un cancer de la prostate \u00e0 s&#8217;appuyer sur un solide groupe de soutien.<\/strong><\/p>\n\n<p class=\"heading-para wp-block-paragraph\">\u00ab M&#8217;habituer \u00e0 vivre avec le cancer a \u00e9t\u00e9 un grand d\u00e9fi. J&#8217;ai \u00e9t\u00e9 largement soutenu par ma famille et mes amis, ainsi que des groupes de soutien associatifs. Au d\u00e9but, j&#8217;\u00e9tais tr\u00e8s inquiet et secou\u00e9. J&#8217;ai appr\u00e9ci\u00e9 de pouvoir parler avec d&#8217;autres personnes pour \u00e9vacuer ces \u00e9motions. Il est important de pouvoir s&#8217;appuyer sur les autres lorsque l&#8217;on re\u00e7oit le diagnostic et le traitement du cancer de la prostate. C&#8217;est aussi agr\u00e9able de pouvoir parler avec ses amis et sa famille de sujets qui ne sont pas li\u00e9s au cancer \u2013 des probl\u00e8mes du quotidien.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">\u00ab\u00a0Je voulais partager mon exp\u00e9rience du quotidien avec un cancer de la prostate pour rassurer les hommes qui re\u00e7oivent un diagnostic\u00a0: ce n&#8217;est pas forc\u00e9ment la fin du monde. Oui, il est normal de paniquer au d\u00e9but. Mais nous sommes bien entour\u00e9s : par l&#8217;\u00e9quipe soignante, les amis, la famille, les groupes de soutien, les organismes de bienfaisance. Et il existe de nombreuses solutions th\u00e9rapeutiques pour traiter le cancer ou prolonger votre vie.\u00a0\u00bb<\/p>\n\n\n<!--Alert Card Layout Start Here-->\n<section class=\"alertcard-section\">\n      <div class=\"container\">\n        <!--Alert Box HTML Start Here-->\n        <div class=\"alert-box info-box\">\n                    <div class=\"info-icon\">\n              <span class=\"info-circle\"><img decoding=\"async\" src=\"https:\/\/www.ipsen.com\/wp-content\/themes\/ipsen-main\/dist\/images\/alert-general-icon.png\" alt=\"Alert\"\/><\/i>\n            <\/div>\n                    <div class=\"info-contents\">\n              <h4 role=\"heading\" aria-level=\"2\" class=\"info-head heading-four heading-four\">\n                                <\/h4>\n              <p class=\"info-sub-head-para visible heading-para\">\n                                <\/p>\n              <div class=\"alert-content visible\">\n                  <p><strong><u>Quelques chiffres sur le cancer de la prostate<\/u><\/strong><\/p>\n<ul>\n<li>1 homme sur 8 sera atteint d&#8217;un cancer de la prostate. Si vous avez plus de 50 ans, si vous \u00eates noir, ou si votre p\u00e8re ou votre fr\u00e8re ont eu un cancer de la prostate, vous \u00eates encore plus \u00e0 risque de d\u00e9velopper ce type de cancer.<\/li>\n<li>Le cancer de la prostate ne met pas toujours la vie du patient en danger. Mais lorsque c&#8217;est le cas, plus t\u00f4t vous recevrez le diagnostic, plus vous aurez de chances de gu\u00e9rir.<\/li>\n<li>Le cancer de la prostate est le 2e cancer le plus fr\u00e9quent chez l&#8217;homme et le 4e cancer le plus fr\u00e9quent parmi tous les cancers.<\/li>\n<li>Plus de 1,4\u00a0million de nouveaux cas de cancer de la prostate ont \u00e9t\u00e9 diagnostiqu\u00e9s en 2020.<\/li>\n<li>Les donn\u00e9es montrent aujourd&#8217;hui que\u00a0:\n<ul>\n<li>\u00eatre en surpoids ou ob\u00e8se AUGMENTE le risque de d\u00e9velopper un cancer avanc\u00e9 de la prostate ;<\/li>\n<li>\u00eatre grand AUGMENTE le risque de d\u00e9velopper un cancer de la prostate<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ednref2\" name=\"_edn2\">[ii]<\/a> https:\/\/prostatecanceruk.org\/<\/p>\n<p><a href=\"#_ednref3\" name=\"_edn3\">[iii]<\/a> https:\/\/www.wcrf.org\/cancer-trends\/prostate-cancer-statistics\/<\/p>\n<p><a href=\"#_ednref4\" name=\"_edn4\">[iv]<\/a> https:\/\/www.wcrf.org\/cancer-trends\/prostate-cancer-statistics\/<\/p>\n<p><a href=\"#_ednref5\" name=\"_edn5\">[v]<\/a> https:\/\/www.wcrf.org\/diet-activity-and-cancer\/risk-factors\/obesity-weight-gain-and-cancer\/<\/p>\n              <\/div>\n          <\/div>\n        <\/div>\n        <!--Alert Box HTML Start Here-->\n      <\/div>\n    <\/section>\n<!--Alert Card Layout End Here-->\n\n","protected":false},"excerpt":{"rendered":"<p>Recevoir un diagnostic de cancer peut \u00eatre accablant. Cependant, les effets du cancer de la prostate peuvent \u00eatre nuanc\u00e9s pour<\/p>\n","protected":false},"author":11,"featured_media":33555,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6024],"tags":[],"class_list":["post-34000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-oncology-fr","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vivre sereinement avec le cancer de la prostate<\/title>\n<meta name=\"description\" content=\"John raconte son quotidien pour rassurer ceux qui pourraient se trouver dans la m\u00eame situation que lui D\u00e9couvrez l\u2019engagement d\u2019Ipsen Oncologie \u00e0 accompagner les patients dans le cadre de traitements innovants.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vivre sereinement avec le cancer de la prostate\" \/>\n<meta property=\"og:description\" content=\"John raconte son quotidien pour rassurer ceux qui pourraient se trouver dans la m\u00eame situation que lui D\u00e9couvrez l\u2019engagement d\u2019Ipsen Oncologie \u00e0 accompagner les patients dans le cadre de traitements innovants.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-26T06:56:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-21T12:43:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/06\/IPSEN-CAPA-Lincoln-078-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1082\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"heloisedetouchet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:site\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"heloisedetouchet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/\"},\"author\":{\"name\":\"heloisedetouchet\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/2c275168b31beee81688f3c041877318\"},\"headline\":\"John raconte son quotidien avec le cancer de la prostate\",\"datePublished\":\"2023-06-26T06:56:53+00:00\",\"dateModified\":\"2024-05-21T12:43:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/\"},\"wordCount\":893,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/IPSEN-CAPA-Lincoln-078-1.jpg\",\"articleSection\":[\"Oncologie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/\",\"name\":\"Vivre sereinement avec le cancer de la prostate\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/IPSEN-CAPA-Lincoln-078-1.jpg\",\"datePublished\":\"2023-06-26T06:56:53+00:00\",\"dateModified\":\"2024-05-21T12:43:40+00:00\",\"description\":\"John raconte son quotidien pour rassurer ceux qui pourraient se trouver dans la m\u00eame situation que lui D\u00e9couvrez l\u2019engagement d\u2019Ipsen Oncologie \u00e0 accompagner les patients dans le cadre de traitements innovants.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/IPSEN-CAPA-Lincoln-078-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/IPSEN-CAPA-Lincoln-078-1.jpg\",\"width\":1082,\"height\":720,\"caption\":\"Photography for Ipsen in Lincoln for Capa Pictures by Ioan Said Photography\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/oncology-fr\\\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"John raconte son quotidien avec le cancer de la prostate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"name\":\"Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\",\"name\":\"IPSEN\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"IPSEN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ipsengroup\",\"https:\\\/\\\/x.com\\\/ipsengroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/2c275168b31beee81688f3c041877318\",\"name\":\"heloisedetouchet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g\",\"caption\":\"heloisedetouchet\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vivre sereinement avec le cancer de la prostate","description":"John raconte son quotidien pour rassurer ceux qui pourraient se trouver dans la m\u00eame situation que lui D\u00e9couvrez l\u2019engagement d\u2019Ipsen Oncologie \u00e0 accompagner les patients dans le cadre de traitements innovants.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/","og_locale":"fr_FR","og_type":"article","og_title":"Vivre sereinement avec le cancer de la prostate","og_description":"John raconte son quotidien pour rassurer ceux qui pourraient se trouver dans la m\u00eame situation que lui D\u00e9couvrez l\u2019engagement d\u2019Ipsen Oncologie \u00e0 accompagner les patients dans le cadre de traitements innovants.","og_url":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/","og_site_name":"Global","article_published_time":"2023-06-26T06:56:53+00:00","article_modified_time":"2024-05-21T12:43:40+00:00","og_image":[{"width":1082,"height":720,"url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/06\/IPSEN-CAPA-Lincoln-078-1.jpg","type":"image\/jpeg"}],"author":"heloisedetouchet","twitter_card":"summary_large_image","twitter_creator":"@ipsengroup","twitter_site":"@ipsengroup","twitter_misc":{"Written by":"heloisedetouchet","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/#article","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/"},"author":{"name":"heloisedetouchet","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/2c275168b31beee81688f3c041877318"},"headline":"John raconte son quotidien avec le cancer de la prostate","datePublished":"2023-06-26T06:56:53+00:00","dateModified":"2024-05-21T12:43:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/"},"wordCount":893,"publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/06\/IPSEN-CAPA-Lincoln-078-1.jpg","articleSection":["Oncologie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/","url":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/","name":"Vivre sereinement avec le cancer de la prostate","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/#primaryimage"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/06\/IPSEN-CAPA-Lincoln-078-1.jpg","datePublished":"2023-06-26T06:56:53+00:00","dateModified":"2024-05-21T12:43:40+00:00","description":"John raconte son quotidien pour rassurer ceux qui pourraient se trouver dans la m\u00eame situation que lui D\u00e9couvrez l\u2019engagement d\u2019Ipsen Oncologie \u00e0 accompagner les patients dans le cadre de traitements innovants.","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/#primaryimage","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/06\/IPSEN-CAPA-Lincoln-078-1.jpg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/06\/IPSEN-CAPA-Lincoln-078-1.jpg","width":1082,"height":720,"caption":"Photography for Ipsen in Lincoln for Capa Pictures by Ioan Said Photography"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/oncology-fr\/john-raconte-son-quotidien-avec-le-cancer-de-la-prostate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/fr\/"},{"@type":"ListItem","position":2,"name":"John raconte son quotidien avec le cancer de la prostate"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/fr\/#website","url":"https:\/\/www.ipsen.com\/fr\/","name":"Global","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/fr\/#organization","name":"IPSEN","url":"https:\/\/www.ipsen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"IPSEN"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ipsengroup","https:\/\/x.com\/ipsengroup"]},{"@type":"Person","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/2c275168b31beee81688f3c041877318","name":"heloisedetouchet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a294050dc7df14814ce352dcd30bd2b11c1bf6f269c4edf2111b59216f02bb15?s=96&d=mm&r=g","caption":"heloisedetouchet"}}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/06\/IPSEN-CAPA-Lincoln-078-1.jpg","_links":{"self":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/34000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/comments?post=34000"}],"version-history":[{"count":4,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/34000\/revisions"}],"predecessor-version":[{"id":56482,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/34000\/revisions\/56482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media\/33555"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media?parent=34000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/categories?post=34000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/tags?post=34000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}