{"id":27784,"date":"2023-02-09T07:06:33","date_gmt":"2023-02-09T05:06:33","guid":{"rendered":"https:\/\/www.ipsen.com\/?p=27784"},"modified":"2023-07-24T13:54:51","modified_gmt":"2023-07-24T11:54:51","slug":"ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew","status":"publish","type":"post","link":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/","title":{"rendered":"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew"},"content":{"rendered":"<p class=\"heading-para wp-block-paragraph\">David\u00a0Loew, Directeur g\u00e9n\u00e9ral d\u2019Ipsen, revient sur les solides r\u00e9sultats de l\u2019exercice\u00a02022 et du quatri\u00e8me\u00a0trimestre\u00a02022.<\/p>\n\n    <section class=\"video-card \">\n        <div class=\"container\">\n            <!-- Block Details -->\n            <div class=\"video-card-header\">\n                <h3 class=\"video-card-block-title hidden heading-three\">\n                                    <\/h3>\n                <p class=\"charcoal-grey video-card-block-summary hidden\"> \n                                    <\/p>\n            <\/div>\n\n            <!-- Video Iframe embed -->\n                            <div class=\"video-embed\"> \n                <iframe loading=\"lazy\" title=\"A word from David_ Sharing the success\" src=\"https:\/\/player.vimeo.com\/video\/847964177?app_id=122963&#038;autoplay=1&#038;muted=1&#038;controls=1&#038;loop=1&#038;autopause=1&#038;background=0\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" id=\"ipsen-video-1\" class=\"veeva_video\" data-ot-ignore><\/iframe>                <\/div>\n            \n            <!-- Block CTA -->\n            <div class=\"cta-block hidden\">\n                            <\/div>\n\n        <\/div>\n    <\/section>\n","protected":false},"excerpt":{"rendered":"<p>David\u00a0Loew, Directeur g\u00e9n\u00e9ral d\u2019Ipsen, revient sur les solides r\u00e9sultats de l\u2019exercice\u00a02022 et du quatri\u00e8me\u00a0trimestre\u00a02022.<\/p>\n","protected":false},"author":9,"featured_media":16686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3515],"tags":[],"class_list":["post-27784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financial-results-fr","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew - Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew - Global\" \/>\n<meta property=\"og:description\" content=\"David\u00a0Loew, Directeur g\u00e9n\u00e9ral d\u2019Ipsen, revient sur les solides r\u00e9sultats de l\u2019exercice\u00a02022 et du quatri\u00e8me\u00a0trimestre\u00a02022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-09T05:06:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T11:54:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/04\/Story_3_Banner.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"konstantinoskampanos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:site\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"konstantinoskampanos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/\"},\"author\":{\"name\":\"konstantinoskampanos\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/caf513ba91f9535b6b2d8a79d95764c5\"},\"headline\":\"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew\",\"datePublished\":\"2023-02-09T05:06:33+00:00\",\"dateModified\":\"2023-07-24T11:54:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/\"},\"wordCount\":50,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Story_3_Banner.png\",\"articleSection\":[\"R\u00e9sultats financiers\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/\",\"name\":\"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew - Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Story_3_Banner.png\",\"datePublished\":\"2023-02-09T05:06:33+00:00\",\"dateModified\":\"2023-07-24T11:54:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Story_3_Banner.png\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Story_3_Banner.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/financial-results-fr\\\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"name\":\"Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\",\"name\":\"IPSEN\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"IPSEN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ipsengroup\",\"https:\\\/\\\/x.com\\\/ipsengroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/caf513ba91f9535b6b2d8a79d95764c5\",\"name\":\"konstantinoskampanos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g\",\"caption\":\"konstantinoskampanos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew - Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/","og_locale":"fr_FR","og_type":"article","og_title":"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew - Global","og_description":"David\u00a0Loew, Directeur g\u00e9n\u00e9ral d\u2019Ipsen, revient sur les solides r\u00e9sultats de l\u2019exercice\u00a02022 et du quatri\u00e8me\u00a0trimestre\u00a02022.","og_url":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/","og_site_name":"Global","article_published_time":"2023-02-09T05:06:33+00:00","article_modified_time":"2023-07-24T11:54:51+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/04\/Story_3_Banner.png","type":"image\/png"}],"author":"konstantinoskampanos","twitter_card":"summary_large_image","twitter_creator":"@ipsengroup","twitter_site":"@ipsengroup","twitter_misc":{"Written by":"konstantinoskampanos","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/#article","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/"},"author":{"name":"konstantinoskampanos","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/caf513ba91f9535b6b2d8a79d95764c5"},"headline":"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew","datePublished":"2023-02-09T05:06:33+00:00","dateModified":"2023-07-24T11:54:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/"},"wordCount":50,"publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/04\/Story_3_Banner.png","articleSection":["R\u00e9sultats financiers"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/","url":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/","name":"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew - Global","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/#primaryimage"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/04\/Story_3_Banner.png","datePublished":"2023-02-09T05:06:33+00:00","dateModified":"2023-07-24T11:54:51+00:00","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/#primaryimage","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/04\/Story_3_Banner.png","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/04\/Story_3_Banner.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/financial-results-fr\/ipsen-publie-ses-resultats-pour-lexercice-2022-et-le-quatrieme-trimestre-2022-un-mot-du-directeur-general-dipsen-david-loew\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Ipsen publie ses r\u00e9sultats pour l\u2019exercice 2022 et le quatri\u00e8me trimestre 2022 \u2013 Un mot du Directeur g\u00e9n\u00e9ral d\u2019Ipsen, David Loew"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/fr\/#website","url":"https:\/\/www.ipsen.com\/fr\/","name":"Global","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/fr\/#organization","name":"IPSEN","url":"https:\/\/www.ipsen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"IPSEN"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ipsengroup","https:\/\/x.com\/ipsengroup"]},{"@type":"Person","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/caf513ba91f9535b6b2d8a79d95764c5","name":"konstantinoskampanos","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g","caption":"konstantinoskampanos"}}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/04\/Story_3_Banner.png","_links":{"self":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/27784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/comments?post=27784"}],"version-history":[{"count":6,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/27784\/revisions"}],"predecessor-version":[{"id":34987,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/27784\/revisions\/34987"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media\/16686"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media?parent=27784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/categories?post=27784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/tags?post=27784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}