{"id":105003,"date":"2026-05-14T07:49:52","date_gmt":"2026-05-14T05:49:52","guid":{"rendered":"https:\/\/www.ipsen.com\/science\/aesthetics-built-from-science-2\/"},"modified":"2026-05-21T12:48:04","modified_gmt":"2026-05-21T10:48:04","slug":"l-esthetique-construite-par-la-science","status":"publish","type":"post","link":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/","title":{"rendered":"L\u2019esth\u00e9tique, construite par la science"},"content":{"rendered":"<p class=\"heading-para wp-block-paragraph\"><em><em>Christelle Huguet, EVP, Directrice R&amp;D<\/em><\/em><\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Ipsen n\u2019est pas un nouvel acteur de l\u2019esth\u00e9tique. Depuis plus de trente ans, nous faisons progresser des innovations en neurosciences \u00e0 travers des indications th\u00e9rapeutiques et esth\u00e9tiques, en d\u00e9veloppant une expertise approfondie dans les biologiques complexes, le d\u00e9veloppement clinique rigoureux et une production de haute qualit\u00e9. Nos m\u00e9dicaments sont approuv\u00e9s pour un usage esth\u00e9tique dans plus de 80 pays \u00e0 travers le monde, gr\u00e2ce \u00e0 notre pr\u00e9sence directe et \u00e0 des partenaires de confiance.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Ce patrimoine est essentiel, car le domaine de l\u2019esth\u00e9tique \u00e9volue, et son avenir sera fa\u00e7onn\u00e9 par la science et les donn\u00e9es.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Chez Ipsen, l\u2019innovation a toujours \u00e9t\u00e9 guid\u00e9e par la compr\u00e9hension. Nous capitalisons sur nos connaissances, apprenons des donn\u00e9es et appliquons la m\u00eame rigueur scientifique aux domaines th\u00e9rapeutique et esth\u00e9tique. Cette approche nous a permis de traduire des d\u00e9cennies de recherche en neurosciences en solutions con\u00e7ues pour r\u00e9pondre \u00e0 des attentes croissantes en mati\u00e8re de qualit\u00e9, de constance et de robustesse clinique.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Aujourd\u2019hui, les attentes \u00e9voluent. Les patients, les consommateurs et les professionnels de sant\u00e9 qui les prennent en charge souhaitent des traitements fond\u00e9s sur des preuves, con\u00e7us avec intention et d\u00e9velopp\u00e9s selon des standards \u00e9lev\u00e9s et constants. Cela exige davantage qu\u2019une innovation incr\u00e9mentale\u202f: cela requiert une compr\u00e9hension biologique profonde, des parcours de d\u00e9veloppement rigoureux et une confiance totale dans la science qui sous\u2011tend chaque d\u00e9cision.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Cette conviction se refl\u00e8te dans nos investissements. Aujourd\u2019hui, 15\u202f% des investissements totaux en R&amp;D d\u2019Ipsen sont consacr\u00e9s aux indications esth\u00e9tiques*. Nous menons actuellement plusieurs \u00e9tudes de Phase\u202fII et de Phase\u202fIII dans des usages esth\u00e9tiques, renfor\u00e7ant ainsi notre ambition de rester un moteur d\u2019innovation significative dans ce domaine.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">L\u2019innovation guid\u00e9e par la science repose \u00e9galement sur la capacit\u00e9 \u00e0 transformer la d\u00e9couverte en r\u00e9alit\u00e9. Les sites de production d\u2019Ipsen disposent de capacit\u00e9s con\u00e7ues pour la prochaine g\u00e9n\u00e9ration de traitements biologiques complexes. Ils incarnent des investissements de long terme dans la qualit\u00e9, la reproductibilit\u00e9 et l\u2019excellence industrielle \u2014 des capacit\u00e9s essentielles lorsque la science passe de l\u2019hypoth\u00e8se au patient.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">L\u2019esth\u00e9tique progresse rapidement. Mais les avanc\u00e9es durables reposent sur des preuves, de l\u2019exp\u00e9rience et une ex\u00e9cution irr\u00e9prochable.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Chez Ipsen, nous continuons \u00e0 fa\u00e7onner l\u2019avenir de l\u2019esth\u00e9tique gr\u00e2ce \u00e0 la recherche fond\u00e9e sur les preuves, des d\u00e9cisions guid\u00e9es par les donn\u00e9es et en nous appuyant sur des d\u00e9cennies d\u2019expertise en neurosciences pour d\u00e9livrer l\u2019innovation.<\/p>\n\n<p class=\"heading-para wp-block-paragraph\"><em>* Correspond aux d\u00e9penses R&amp;D d\u2019Ipsen projet\u00e9es pour 2026. Donn\u00e9e interne, f\u00e9vrier\u202f2026.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Christelle Huguet, EVP, Directrice R&amp;D Ipsen n\u2019est pas un nouvel acteur de l\u2019esth\u00e9tique. Depuis plus de trente ans, nous faisons<\/p>\n","protected":false},"author":9,"featured_media":105005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1193],"tags":[],"class_list":["post-105003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-neuroscience-fr","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019esth\u00e9tique, construite par la science - Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019esth\u00e9tique, construite par la science - Global\" \/>\n<meta property=\"og:description\" content=\"Christelle Huguet, EVP, Directrice R&amp;D Ipsen n\u2019est pas un nouvel acteur de l\u2019esth\u00e9tique. Depuis plus de trente ans, nous faisons\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-14T05:49:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-21T10:48:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/05\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"756\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"konstantinoskampanos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:site\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"konstantinoskampanos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/\"},\"author\":{\"name\":\"konstantinoskampanos\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/caf513ba91f9535b6b2d8a79d95764c5\"},\"headline\":\"L\u2019esth\u00e9tique, construite par la science\",\"datePublished\":\"2026-05-14T05:49:52+00:00\",\"dateModified\":\"2026-05-21T10:48:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/\"},\"wordCount\":484,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg\",\"articleSection\":[\"Neurosciences\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/\",\"name\":\"L\u2019esth\u00e9tique, construite par la science - Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg\",\"datePublished\":\"2026-05-14T05:49:52+00:00\",\"dateModified\":\"2026-05-21T10:48:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg\",\"width\":756,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/neuroscience-fr\\\/l-esthetique-construite-par-la-science\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019esth\u00e9tique, construite par la science\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"name\":\"Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\",\"name\":\"IPSEN\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"IPSEN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ipsengroup\",\"https:\\\/\\\/x.com\\\/ipsengroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/caf513ba91f9535b6b2d8a79d95764c5\",\"name\":\"konstantinoskampanos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g\",\"caption\":\"konstantinoskampanos\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019esth\u00e9tique, construite par la science - Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019esth\u00e9tique, construite par la science - Global","og_description":"Christelle Huguet, EVP, Directrice R&amp;D Ipsen n\u2019est pas un nouvel acteur de l\u2019esth\u00e9tique. Depuis plus de trente ans, nous faisons","og_url":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/","og_site_name":"Global","article_published_time":"2026-05-14T05:49:52+00:00","article_modified_time":"2026-05-21T10:48:04+00:00","og_image":[{"width":756,"height":506,"url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/05\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg","type":"image\/jpeg"}],"author":"konstantinoskampanos","twitter_card":"summary_large_image","twitter_creator":"@ipsengroup","twitter_site":"@ipsengroup","twitter_misc":{"Written by":"konstantinoskampanos","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/#article","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/"},"author":{"name":"konstantinoskampanos","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/caf513ba91f9535b6b2d8a79d95764c5"},"headline":"L\u2019esth\u00e9tique, construite par la science","datePublished":"2026-05-14T05:49:52+00:00","dateModified":"2026-05-21T10:48:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/"},"wordCount":484,"publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/05\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg","articleSection":["Neurosciences"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/","url":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/","name":"L\u2019esth\u00e9tique, construite par la science - Global","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/#primaryimage"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/05\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg","datePublished":"2026-05-14T05:49:52+00:00","dateModified":"2026-05-21T10:48:04+00:00","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/#primaryimage","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/05\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/05\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg","width":756,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/neuroscience-fr\/l-esthetique-construite-par-la-science\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019esth\u00e9tique, construite par la science"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/fr\/#website","url":"https:\/\/www.ipsen.com\/fr\/","name":"Global","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/fr\/#organization","name":"IPSEN","url":"https:\/\/www.ipsen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"IPSEN"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ipsengroup","https:\/\/x.com\/ipsengroup"]},{"@type":"Person","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/caf513ba91f9535b6b2d8a79d95764c5","name":"konstantinoskampanos","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/461d8aaa3dc000968b96f9df6ebfd0f045990cabf9f91de7f7dc4b9542e2adc8?s=96&d=mm&r=g","caption":"konstantinoskampanos"}}]}},"jetpack_featured_media_url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/05\/ELT-member_Christelle-HUGUET_IPSEN-COM_756x506pix_fe946a.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/105003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/comments?post=105003"}],"version-history":[{"count":6,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/105003\/revisions"}],"predecessor-version":[{"id":105014,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/105003\/revisions\/105014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media\/105005"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media?parent=105003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/categories?post=105003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/tags?post=105003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}