{"id":101637,"date":"2026-03-16T15:47:27","date_gmt":"2026-03-16T13:47:27","guid":{"rendered":"https:\/\/www.ipsen.com\/?p=101637"},"modified":"2026-03-16T15:52:44","modified_gmt":"2026-03-16T13:52:44","slug":"une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements","status":"publish","type":"post","link":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/","title":{"rendered":"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0"},"content":{"rendered":"<p class=\"heading-para wp-block-paragraph\">Nouvelle dans\u00a0notre\u00a0s\u00e9rie\u00a0<em>Une vie dans la science<\/em>, nous\u00a0rencontrons\u00a0Audrey\u00a0Clap\u00e9ron, Translational Biology Director, qui\u00a0\u00e9voque\u00a0le\u00a0r\u00f4le\u00a0essentiel\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0de la recherche. Elle\u00a0explique\u00a0comment\u00a0diriger\u00a0une\u00a0\u00e9quipe de\u00a0pharmacologues\u00a0et\u00a0fournir\u00a0des donn\u00e9es de haute\u00a0qualit\u00e9\u00a0pour le\u00a0d\u00e9veloppement\u00a0clinique\u00a0la motive\u00a0chaque\u00a0jour et la garde\u00a0proche\u00a0des patients qui\u00a0pourront\u00a0un jour\u00a0en\u00a0b\u00e9n\u00e9ficier.\u00a0<\/p>\n\n    <section class=\"video-card \">\n        <div class=\"container\">\n            <!-- Block Details -->\n            <div class=\"video-card-header\">\n                <h3 class=\"video-card-block-title hidden heading-three\">\n                                    <\/h3>\n                <p class=\"charcoal-grey video-card-block-summary hidden\"> \n                                    <\/p>\n            <\/div>\n\n            <!-- Video Iframe embed -->\n                            <div class=\"video-embed\"> \n                <iframe loading=\"lazy\" title=\"13885-IPS-Life In Science-Wave 2-Audrey Clap\u00e9ron-03-FR\" src=\"https:\/\/player.vimeo.com\/video\/1174020353?app_id=122963&#038;autoplay=1&#038;muted=1&#038;controls=1&#038;loop=1&#038;autopause=1&#038;background=0\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write; encrypted-media; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" id=\"ipsen-video-1\" class=\"veeva_video\" data-ot-ignore><\/iframe>                <\/div>\n            \n            <!-- Block CTA -->\n            <div class=\"cta-block hidden\">\n                            <\/div>\n\n        <\/div>\n    <\/section>\n\n\n<p class=\"heading-para wp-block-paragraph\">\u00ab Les donn\u00e9es\u00a0sont\u00a0vraiment\u00a0\u00e0 la base de tout. Elles\u00a0apportent\u00a0des\u00a0preuves\u00a0objectives pour la\u00a0prise\u00a0de\u00a0d\u00e9cision\u00a0et\u00a0sont\u00a0donc\u00a0essentielles\u00a0pour le\u00a0projet\u00a0\u00bb,\u00a0explique\u00a0Audrey\u00a0Clap\u00e9ron, Translational Biology Director chez Ipsen.\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Son travail\u00a0consiste\u00a0\u00e0\u00a0veiller\u00a0\u00e0\u00a0ce\u00a0que\u00a0chaque\u00a0projet\u00a0repose sur des\u00a0r\u00e9sultats\u00a0fiables. \u00ab Mon\u00a0quotidien\u00a0consiste\u00a0\u00e0\u00a0m\u2019assurer\u00a0que\u00a0toutes\u00a0les donn\u00e9es\u00a0pharmacologiques\u00a0sont\u00a0fournies\u00a0au\u00a0projet. Je dirige\u00a0\u00e9galement\u00a0une\u00a0\u00e9quipe de\u00a0pharmacologues\u00a0in vivo et in vitro. \u00bb\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Ces\u00a0donn\u00e9es ne\u00a0sont\u00a0pas\u00a0abstraites\u00a0:\u00a0elles\u00a0sont\u00a0essentielles\u00a0pour faire\u00a0progresser\u00a0les\u00a0d\u00e9couvertes. \u00ab Nous\u00a0sommes\u00a0tr\u00e8s\u00a0proches\u00a0des patients, car nous\u00a0fournissons\u00a0des\u00a0preuves\u00a0et des donn\u00e9es pour le\u00a0d\u00e9veloppement\u00a0clinique\u00a0; les patients\u00a0sont\u00a0presque\u00a0ici\u00a0avec nous. \u00bb\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">Ce sentiment de\u00a0proximit\u00e9\u00a0avec les patients guide la mani\u00e8re\u00a0dont\u00a0Audrey et son \u00e9quipe\u00a0rel\u00e8vent\u00a0les\u00a0d\u00e9fis. \u00ab Quand les choses\u00a0deviennent\u00a0complexes, je\u00a0reviens\u00a0toujours\u00a0aux\u00a0priorit\u00e9s\u00a0du\u00a0projet\u00a0:\u00a0fournir\u00a0de nouveaux\u00a0m\u00e9dicaments\u00a0innovants\u00a0aux patients,\u00a0\u00e9tablir\u00a0des\u00a0priorit\u00e9s\u00a0si\u00a0n\u00e9cessaire,\u00a0communiquer\u00a0avec\u00a0l\u2019\u00e9quipe\u00a0et\u00a0offrir\u00a0une\u00a0vision claire pour\u00a0que\u00a0le\u00a0projet\u00a0puisse\u00a0avancer. \u00bb\u00a0<\/p>\n\n<p class=\"heading-para wp-block-paragraph\">La perspective\u00a0d\u2019Audrey\u00a0montre\u00a0que\u00a0les donn\u00e9es ne\u00a0sont\u00a0pas\u00a0qu\u2019une\u00a0source\u00a0d\u2019information\u00a0:\u00a0<br>elles\u00a0sont\u00a0la\u00a0preuve\u00a0qui\u00a0permet\u00a0aux\u00a0m\u00e9dicaments\u00a0de\u00a0progresser, avec les patients\u00a0toujours\u00a0au\u00a0centre.\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>Nouvelle dans\u00a0notre\u00a0s\u00e9rie\u00a0Une vie dans la science, nous\u00a0rencontrons\u00a0Audrey\u00a0Clap\u00e9ron, Translational Biology Director, qui\u00a0\u00e9voque\u00a0le\u00a0r\u00f4le\u00a0essentiel\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0de la recherche. Elle\u00a0explique\u00a0comment\u00a0diriger\u00a0une\u00a0\u00e9quipe de\u00a0pharmacologues\u00a0et\u00a0fournir\u00a0des donn\u00e9es de haute\u00a0qualit\u00e9\u00a0pour<\/p>\n","protected":false},"author":97,"featured_media":101635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[81827],"tags":[],"class_list":["post-101637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-science-2","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0 - Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0 - Global\" \/>\n<meta property=\"og:description\" content=\"Nouvelle dans\u00a0notre\u00a0s\u00e9rie\u00a0Une vie dans la science, nous\u00a0rencontrons\u00a0Audrey\u00a0Clap\u00e9ron, Translational Biology Director, qui\u00a0\u00e9voque\u00a0le\u00a0r\u00f4le\u00a0essentiel\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0de la recherche. Elle\u00a0explique\u00a0comment\u00a0diriger\u00a0une\u00a0\u00e9quipe de\u00a0pharmacologues\u00a0et\u00a0fournir\u00a0des donn\u00e9es de haute\u00a0qualit\u00e9\u00a0pour\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-16T13:47:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-16T13:52:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/03\/Audrey.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"620\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"emie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:site\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"emie\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/\"},\"author\":{\"name\":\"emie\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/a0f231a95044132e1295dd6b00f339b4\"},\"headline\":\"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0\",\"datePublished\":\"2026-03-16T13:47:27+00:00\",\"dateModified\":\"2026-03-16T13:52:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/\"},\"wordCount\":462,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Audrey.png\",\"articleSection\":[\"Science\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/\",\"name\":\"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0 - Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Audrey.png\",\"datePublished\":\"2026-03-16T13:47:27+00:00\",\"dateModified\":\"2026-03-16T13:52:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Audrey.png\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Audrey.png\",\"width\":1080,\"height\":620},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/actualites\\\/science-2\\\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"name\":\"Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\",\"name\":\"IPSEN\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"IPSEN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ipsengroup\",\"https:\\\/\\\/x.com\\\/ipsengroup\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/person\\\/a0f231a95044132e1295dd6b00f339b4\",\"name\":\"emie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3bc24640199849cf7c9cfaa79cb49dc93e3d4e03a9e50a0dc791bd1a408a70f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3bc24640199849cf7c9cfaa79cb49dc93e3d4e03a9e50a0dc791bd1a408a70f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e3bc24640199849cf7c9cfaa79cb49dc93e3d4e03a9e50a0dc791bd1a408a70f?s=96&d=mm&r=g\",\"caption\":\"emie\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0 - Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/","og_locale":"fr_FR","og_type":"article","og_title":"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0 - Global","og_description":"Nouvelle dans\u00a0notre\u00a0s\u00e9rie\u00a0Une vie dans la science, nous\u00a0rencontrons\u00a0Audrey\u00a0Clap\u00e9ron, Translational Biology Director, qui\u00a0\u00e9voque\u00a0le\u00a0r\u00f4le\u00a0essentiel\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0de la recherche. Elle\u00a0explique\u00a0comment\u00a0diriger\u00a0une\u00a0\u00e9quipe de\u00a0pharmacologues\u00a0et\u00a0fournir\u00a0des donn\u00e9es de haute\u00a0qualit\u00e9\u00a0pour","og_url":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/","og_site_name":"Global","article_published_time":"2026-03-16T13:47:27+00:00","article_modified_time":"2026-03-16T13:52:44+00:00","og_image":[{"width":1080,"height":620,"url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/03\/Audrey.png","type":"image\/png"}],"author":"emie","twitter_card":"summary_large_image","twitter_creator":"@ipsengroup","twitter_site":"@ipsengroup","twitter_misc":{"Written by":"emie","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/#article","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/"},"author":{"name":"emie","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/a0f231a95044132e1295dd6b00f339b4"},"headline":"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0","datePublished":"2026-03-16T13:47:27+00:00","dateModified":"2026-03-16T13:52:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/"},"wordCount":462,"publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/03\/Audrey.png","articleSection":["Science"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/","url":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/","name":"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0 - Global","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/#primaryimage"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/03\/Audrey.png","datePublished":"2026-03-16T13:47:27+00:00","dateModified":"2026-03-16T13:52:44+00:00","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/#primaryimage","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/03\/Audrey.png","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/03\/Audrey.png","width":1080,"height":620},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/fr\/actualites\/science-2\/une-vie-dans-la-science-le-role-des-donnees-dans-lavancee-des-traitements\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Une vie dans la science: Le\u00a0r\u00f4le\u00a0des donn\u00e9es dans\u00a0l\u2019avanc\u00e9e\u00a0des\u00a0traitements\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/fr\/#website","url":"https:\/\/www.ipsen.com\/fr\/","name":"Global","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/fr\/#organization","name":"IPSEN","url":"https:\/\/www.ipsen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"IPSEN"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ipsengroup","https:\/\/x.com\/ipsengroup"]},{"@type":"Person","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/person\/a0f231a95044132e1295dd6b00f339b4","name":"emie","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/e3bc24640199849cf7c9cfaa79cb49dc93e3d4e03a9e50a0dc791bd1a408a70f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e3bc24640199849cf7c9cfaa79cb49dc93e3d4e03a9e50a0dc791bd1a408a70f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e3bc24640199849cf7c9cfaa79cb49dc93e3d4e03a9e50a0dc791bd1a408a70f?s=96&d=mm&r=g","caption":"emie"}}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2026\/03\/Audrey.png","_links":{"self":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/101637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/comments?post=101637"}],"version-history":[{"count":3,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/101637\/revisions"}],"predecessor-version":[{"id":101646,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/posts\/101637\/revisions\/101646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media\/101635"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media?parent=101637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/categories?post=101637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/tags?post=101637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}