{"id":81371,"date":"2025-06-19T16:29:06","date_gmt":"2025-06-19T14:29:06","guid":{"rendered":"https:\/\/www.ipsen.com\/?post_type=lay_language&#038;p=81371"},"modified":"2025-08-21T09:06:20","modified_gmt":"2025-08-21T07:06:20","slug":"etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine","status":"publish","type":"lay_language","link":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/","title":{"rendered":"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne"},"content":{"rendered":"\n<p>Palovarot\u00e8ne<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":97,"template":"","lay_language_category":[70160],"class_list":["post-81371","lay_language","type-lay_language","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne - Global<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne - Global\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Global\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-21T07:06:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/11\/72x72-Lay-Summaries-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"73\" \/>\n\t<meta property=\"og:image:height\" content=\"73\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ipsengroup\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/\",\"name\":\"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne - Global\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/72x72-Lay-Summaries-1.png\",\"datePublished\":\"2025-06-19T14:29:06+00:00\",\"dateModified\":\"2025-08-21T07:06:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/72x72-Lay-Summaries-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/72x72-Lay-Summaries-1.png\",\"width\":73,\"height\":73},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/lay-language\\\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"name\":\"Global\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#organization\",\"name\":\"IPSEN\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"contentUrl\":\"https:\\\/\\\/www.ipsen.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Latest_Ipsen-logo_168x48.svg\",\"caption\":\"IPSEN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ipsen.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Ipsengroup\",\"https:\\\/\\\/x.com\\\/ipsengroup\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne - Global","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne - Global","og_url":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/","og_site_name":"Global","article_modified_time":"2025-08-21T07:06:20+00:00","og_image":[{"width":73,"height":73,"url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/11\/72x72-Lay-Summaries-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ipsengroup","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/","url":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/","name":"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne - Global","isPartOf":{"@id":"https:\/\/www.ipsen.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/#primaryimage"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/11\/72x72-Lay-Summaries-1.png","datePublished":"2025-06-19T14:29:06+00:00","dateModified":"2025-08-21T07:06:20+00:00","breadcrumb":{"@id":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/#primaryimage","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/11\/72x72-Lay-Summaries-1.png","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2024\/11\/72x72-Lay-Summaries-1.png","width":73,"height":73},{"@type":"BreadcrumbList","@id":"https:\/\/www.ipsen.com\/fr\/lay-language\/etude-de-suivi-visant-a-en-apprendre-davantage-sur-les-effets-du-palovarotene-chez-les-personnes-agees-de-plus-de-14-ans-atteintes-de-fibrodysplasie-ossifiante-progressive-fop-ayant-termine-certaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ipsen.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"\u00c9tude de suivi visant \u00e0 en apprendre davantage sur les effets du palovarot\u00e8ne chez les personnes \u00e2g\u00e9es de plus de 14 ans atteintes de fibrodysplasie ossifiante progressive (FOP) ayant termin\u00e9 certaines \u00e9tudes ant\u00e9rieures sur le palovarot\u00e8ne"}]},{"@type":"WebSite","@id":"https:\/\/www.ipsen.com\/fr\/#website","url":"https:\/\/www.ipsen.com\/fr\/","name":"Global","description":"","publisher":{"@id":"https:\/\/www.ipsen.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ipsen.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ipsen.com\/fr\/#organization","name":"IPSEN","url":"https:\/\/www.ipsen.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","contentUrl":"https:\/\/www.ipsen.com\/wp-content\/uploads\/2023\/12\/Latest_Ipsen-logo_168x48.svg","caption":"IPSEN"},"image":{"@id":"https:\/\/www.ipsen.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Ipsengroup","https:\/\/x.com\/ipsengroup"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/lay_language\/81371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/lay_language"}],"about":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/types\/lay_language"}],"author":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/users\/97"}],"version-history":[{"count":1,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/lay_language\/81371\/revisions"}],"predecessor-version":[{"id":81372,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/lay_language\/81371\/revisions\/81372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media\/71083"}],"wp:attachment":[{"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/media?parent=81371"}],"wp:term":[{"taxonomy":"lay_language_category","embeddable":true,"href":"https:\/\/www.ipsen.com\/fr\/wp-json\/wp\/v2\/lay_language_category?post=81371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}